{"id":20271,"date":"2026-09-02T14:53:38","date_gmt":"2026-09-02T12:53:38","guid":{"rendered":"https:\/\/www.studiobrancaleone.it\/news\/?p=20271"},"modified":"2026-09-02T14:54:49","modified_gmt":"2026-09-02T12:54:49","slug":"mase-reflui-da-lavaggio-dei-contenitori-stradali","status":"publish","type":"post","link":"https:\/\/www.studiobrancaleone.it\/news\/mase-reflui-da-lavaggio-dei-contenitori-stradali\/","title":{"rendered":"Mase, reflui da lavaggio dei contenitori stradali"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Il Mase, in risposta ad interpello, fornisce chiarimenti in merito alla <strong>classificazione del refluo derivante dal lavaggio dei contenitori stradali<\/strong> adibiti alla raccolta dei rifiuti urbani.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Quesito<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il Comune di Calliano Monferrato chiede al Ministero chiarimenti sulla <strong>classificazione del refluo derivante dal lavaggio dei contenitori stradali<\/strong> per la raccolta dei rifiuti urbani, in particolare:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>se il lavaggio <strong>della parte esterna<\/strong> delle campane del vetro possa essere <strong>assimilato ai lavaggi del sedime stradale<\/strong> o degli arredi urbani;<\/li>\n\n\n\n<li>se l\u2019<strong>eventuale (irrisoria) produzione di reflui<\/strong>, non a contatto con i rifiuti, possa essere considerata <strong>\u201ca perdere\u201d<\/strong> e non classificata come rifiuto liquido.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Risposta Mase<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Il Ministero, innazitutto, ricorda che il <strong>lavaggio dei contenitori stradali<\/strong> \u00e8, di regola, disciplinata dal capitolato speciale d&#8217;appalto del servizio di igiene urbana e dal relativo contratto di servizio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le operazioni di lavaggio dei contenitori stradali <strong>possono essere eseguite mediante differenti modalit\u00e0 operative<\/strong>, tra cui l&#8217;impiego di veicoli &#8220;<strong>lavacassonetti<\/strong>\u201d dotati di sistemi di recupero delle acque di lavaggio. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In tale ipotesi, il mezzo \u00e8 <strong>provvisto di dispositivi di aspirazione che consentono la raccolta separata delle acque<\/strong> generate dalle operazioni di lavaggio all&#8217;interno dello stesso veicolo e <strong>tali acque<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>sono da considerarsi <strong>rifiuti speciali allo stato liquido<\/strong>, in quanto non ricorrono i presupposti per l\u2019applicazione del concetto di scarico;<\/li>\n\n\n\n<li>sono successivamente <strong>avviate a trattamento<\/strong> presso impianti autorizzati.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">In merito al <strong>lavaggio esterno delle campane del vetro con lancia ad alta pressione<\/strong>, il Ministero ritiene che:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>le acque <strong>non possono essere assimilate alle acque meteoriche<\/strong>, in quanto derivanti da un\u2019attivit\u00e0 di manutenzione dell\u2019infrastruttura per la raccolta dei rifiuti;<\/li>\n\n\n\n<li><strong>devono essere intercettate<\/strong> con dispositivi adeguati (es. aspirazione) e conferite in impianti autorizzati al trattamento dei rifiuti liquidi.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">In ogni caso, ferma restando la disciplina dettata dai capitolati del servizio di igiene urbana e le altre disposizioni regionali e locali applicabili, il Ministero evidenzia che <strong>tali operazioni dovrebbero<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>evitare il ristagno<\/strong> sulle sedi stradali delle acque di lavaggio;<\/li>\n\n\n\n<li>garantire che l\u2019acqua <strong>non entri in contatto con residui<\/strong> o superfici interne del contenitore;<\/li>\n\n\n\n<li>essere svolte su contenitori <strong>svuotati, integri e sigillati<\/strong>;<\/li>\n\n\n\n<li>eventualmente utilizzare <strong>sistemi di lavaggio a secco<\/strong>, che non generano reflui.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-ast-global-color-0-color has-alpha-channel-opacity has-ast-global-color-0-background-color has-background is-style-wide\"\/>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/www.mase.gov.it\/portale\/documents\/d\/guest\/2026_09_02_interp_ecb_calliano_monferrato_riscontro-pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Mase, risposta ad interpello n. 169348 del 6\/8\/2026<\/a><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Indicazioni in merito a interpello ex art. 3-septies del d.lgs. 152\/2006 &#8211; Chiarimenti in ordine alla classificazione del refluo derivante dal lavaggio dei contenitori stradali adibiti alla raccolta dei rifiuti urbani.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Mase, in risposta ad interpello, fornisce chiarimenti in merito alla classificazione del refluo derivante dal lavaggio dei contenitori stradali adibiti alla raccolta dei rifiuti urbani. Quesito Il Comune di Calliano Monferrato chiede al Ministero chiarimenti sulla classificazione del refluo derivante dal lavaggio dei contenitori stradali per la raccolta dei rifiuti urbani, in particolare: Risposta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4],"tags":[96,32],"class_list":["post-20271","post","type-post","status-publish","format-standard","hentry","category-nazionali-ue","tag-acque","tag-rifiuti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Mase, reflui da lavaggio dei contenitori stradali &#060; Studio Brancaleone<\/title>\r\n<meta name=\"description\" content=\"Il Mase fornisce chiarimenti in merito alla classificazione del refluo derivante dal lavaggio dei contenitori stradali adibiti alla raccolta dei rifiuti urbani.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.studiobrancaleone.it\/news\/mase-reflui-da-lavaggio-dei-contenitori-stradali\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Mase, reflui da lavaggio dei contenitori stradali &#060; Studio Brancaleone\" \/>\r\n<meta property=\"og:description\" content=\"Il Mase fornisce chiarimenti in merito alla classificazione del refluo derivante dal lavaggio dei contenitori stradali adibiti alla raccolta dei rifiuti urbani.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.studiobrancaleone.it\/news\/mase-reflui-da-lavaggio-dei-contenitori-stradali\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Studio Brancaleone\" \/>\r\n<meta property=\"article:published_time\" content=\"2026-09-02T12:53:38+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2026-09-02T12:54:49+00:00\" \/>\r\n<meta name=\"author\" content=\"Giorgio Ferrari\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giorgio Ferrari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/mase-reflui-da-lavaggio-dei-contenitori-stradali\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/mase-reflui-da-lavaggio-dei-contenitori-stradali\\\/\"},\"author\":{\"name\":\"Giorgio Ferrari\",\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/#\\\/schema\\\/person\\\/da5920864810e22fb65389a0a5cff7e3\"},\"headline\":\"Mase, reflui da lavaggio dei contenitori stradali\",\"datePublished\":\"2026-09-02T12:53:38+00:00\",\"dateModified\":\"2026-09-02T12:54:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/mase-reflui-da-lavaggio-dei-contenitori-stradali\\\/\"},\"wordCount\":398,\"publisher\":{\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/#organization\"},\"keywords\":[\"Acque\",\"Rifiuti\"],\"articleSection\":[\"Nazionali\\\/Ue\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/mase-reflui-da-lavaggio-dei-contenitori-stradali\\\/\",\"url\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/mase-reflui-da-lavaggio-dei-contenitori-stradali\\\/\",\"name\":\"Mase, reflui da lavaggio dei contenitori stradali &#060; Studio Brancaleone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/#website\"},\"datePublished\":\"2026-09-02T12:53:38+00:00\",\"dateModified\":\"2026-09-02T12:54:49+00:00\",\"description\":\"Il Mase fornisce chiarimenti in merito alla classificazione del refluo derivante dal lavaggio dei contenitori stradali adibiti alla raccolta dei rifiuti urbani.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/mase-reflui-da-lavaggio-dei-contenitori-stradali\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/mase-reflui-da-lavaggio-dei-contenitori-stradali\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/mase-reflui-da-lavaggio-dei-contenitori-stradali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mase, reflui da lavaggio dei contenitori stradali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/\",\"name\":\"Studio Brancaleone\",\"description\":\"Notizie giuridiche aggiornate regolarmente\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/#organization\",\"name\":\"Studio Brancaleone\",\"url\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Testata-sito-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Testata-sito-scaled.webp\",\"width\":2560,\"height\":481,\"caption\":\"Studio Brancaleone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/#\\\/schema\\\/person\\\/da5920864810e22fb65389a0a5cff7e3\",\"name\":\"Giorgio Ferrari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5a8c666e3c03788ccd80843664b7c6eb2fb548eb37bb5cd6598134bf5d56ae1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5a8c666e3c03788ccd80843664b7c6eb2fb548eb37bb5cd6598134bf5d56ae1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5a8c666e3c03788ccd80843664b7c6eb2fb548eb37bb5cd6598134bf5d56ae1?s=96&d=mm&r=g\",\"caption\":\"Giorgio Ferrari\"},\"sameAs\":[\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\"],\"url\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/author\\\/giorfer\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mase, reflui da lavaggio dei contenitori stradali &#060; Studio Brancaleone","description":"Il Mase fornisce chiarimenti in merito alla classificazione del refluo derivante dal lavaggio dei contenitori stradali adibiti alla raccolta dei rifiuti urbani.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.studiobrancaleone.it\/news\/mase-reflui-da-lavaggio-dei-contenitori-stradali\/","og_locale":"it_IT","og_type":"article","og_title":"Mase, reflui da lavaggio dei contenitori stradali &#060; Studio Brancaleone","og_description":"Il Mase fornisce chiarimenti in merito alla classificazione del refluo derivante dal lavaggio dei contenitori stradali adibiti alla raccolta dei rifiuti urbani.","og_url":"https:\/\/www.studiobrancaleone.it\/news\/mase-reflui-da-lavaggio-dei-contenitori-stradali\/","og_site_name":"Studio Brancaleone","article_published_time":"2026-09-02T12:53:38+00:00","article_modified_time":"2026-09-02T12:54:49+00:00","author":"Giorgio Ferrari","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Giorgio Ferrari","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.studiobrancaleone.it\/news\/mase-reflui-da-lavaggio-dei-contenitori-stradali\/#article","isPartOf":{"@id":"https:\/\/www.studiobrancaleone.it\/news\/mase-reflui-da-lavaggio-dei-contenitori-stradali\/"},"author":{"name":"Giorgio Ferrari","@id":"https:\/\/www.studiobrancaleone.it\/news\/#\/schema\/person\/da5920864810e22fb65389a0a5cff7e3"},"headline":"Mase, reflui da lavaggio dei contenitori stradali","datePublished":"2026-09-02T12:53:38+00:00","dateModified":"2026-09-02T12:54:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.studiobrancaleone.it\/news\/mase-reflui-da-lavaggio-dei-contenitori-stradali\/"},"wordCount":398,"publisher":{"@id":"https:\/\/www.studiobrancaleone.it\/news\/#organization"},"keywords":["Acque","Rifiuti"],"articleSection":["Nazionali\/Ue"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.studiobrancaleone.it\/news\/mase-reflui-da-lavaggio-dei-contenitori-stradali\/","url":"https:\/\/www.studiobrancaleone.it\/news\/mase-reflui-da-lavaggio-dei-contenitori-stradali\/","name":"Mase, reflui da lavaggio dei contenitori stradali &#060; Studio Brancaleone","isPartOf":{"@id":"https:\/\/www.studiobrancaleone.it\/news\/#website"},"datePublished":"2026-09-02T12:53:38+00:00","dateModified":"2026-09-02T12:54:49+00:00","description":"Il Mase fornisce chiarimenti in merito alla classificazione del refluo derivante dal lavaggio dei contenitori stradali adibiti alla raccolta dei rifiuti urbani.","breadcrumb":{"@id":"https:\/\/www.studiobrancaleone.it\/news\/mase-reflui-da-lavaggio-dei-contenitori-stradali\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.studiobrancaleone.it\/news\/mase-reflui-da-lavaggio-dei-contenitori-stradali\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.studiobrancaleone.it\/news\/mase-reflui-da-lavaggio-dei-contenitori-stradali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.studiobrancaleone.it\/news\/"},{"@type":"ListItem","position":2,"name":"Mase, reflui da lavaggio dei contenitori stradali"}]},{"@type":"WebSite","@id":"https:\/\/www.studiobrancaleone.it\/news\/#website","url":"https:\/\/www.studiobrancaleone.it\/news\/","name":"Studio Brancaleone","description":"Notizie giuridiche aggiornate regolarmente","publisher":{"@id":"https:\/\/www.studiobrancaleone.it\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.studiobrancaleone.it\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.studiobrancaleone.it\/news\/#organization","name":"Studio Brancaleone","url":"https:\/\/www.studiobrancaleone.it\/news\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.studiobrancaleone.it\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.studiobrancaleone.it\/news\/wp-content\/uploads\/2025\/02\/Testata-sito-scaled.webp","contentUrl":"https:\/\/www.studiobrancaleone.it\/news\/wp-content\/uploads\/2025\/02\/Testata-sito-scaled.webp","width":2560,"height":481,"caption":"Studio Brancaleone"},"image":{"@id":"https:\/\/www.studiobrancaleone.it\/news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.studiobrancaleone.it\/news\/#\/schema\/person\/da5920864810e22fb65389a0a5cff7e3","name":"Giorgio Ferrari","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e5a8c666e3c03788ccd80843664b7c6eb2fb548eb37bb5cd6598134bf5d56ae1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e5a8c666e3c03788ccd80843664b7c6eb2fb548eb37bb5cd6598134bf5d56ae1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5a8c666e3c03788ccd80843664b7c6eb2fb548eb37bb5cd6598134bf5d56ae1?s=96&d=mm&r=g","caption":"Giorgio Ferrari"},"sameAs":["https:\/\/www.studiobrancaleone.it\/news"],"url":"https:\/\/www.studiobrancaleone.it\/news\/author\/giorfer\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Giorgio Ferrari","author_link":"https:\/\/www.studiobrancaleone.it\/news\/author\/giorfer\/"},"uagb_comment_info":0,"uagb_excerpt":"Il Mase, in risposta ad interpello, fornisce chiarimenti in merito alla classificazione del refluo derivante dal lavaggio dei contenitori stradali adibiti alla raccolta dei rifiuti urbani. Quesito Il Comune di Calliano Monferrato chiede al Ministero chiarimenti sulla classificazione del refluo derivante dal lavaggio dei contenitori stradali per la raccolta dei rifiuti urbani, in particolare: Risposta&hellip;","_links":{"self":[{"href":"https:\/\/www.studiobrancaleone.it\/news\/wp-json\/wp\/v2\/posts\/20271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiobrancaleone.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiobrancaleone.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiobrancaleone.it\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiobrancaleone.it\/news\/wp-json\/wp\/v2\/comments?post=20271"}],"version-history":[{"count":1,"href":"https:\/\/www.studiobrancaleone.it\/news\/wp-json\/wp\/v2\/posts\/20271\/revisions"}],"predecessor-version":[{"id":20272,"href":"https:\/\/www.studiobrancaleone.it\/news\/wp-json\/wp\/v2\/posts\/20271\/revisions\/20272"}],"wp:attachment":[{"href":"https:\/\/www.studiobrancaleone.it\/news\/wp-json\/wp\/v2\/media?parent=20271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiobrancaleone.it\/news\/wp-json\/wp\/v2\/categories?post=20271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiobrancaleone.it\/news\/wp-json\/wp\/v2\/tags?post=20271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}