{"id":9323,"date":"2023-05-15T09:00:45","date_gmt":"2023-05-15T07:00:45","guid":{"rendered":"https:\/\/www.studiobrancaleone.it\/news\/?p=9323"},"modified":"2025-01-26T19:01:54","modified_gmt":"2025-01-26T18:01:54","slug":"raee-chiarimenti-cdc-su-nuovi-raggruppamenti","status":"publish","type":"post","link":"https:\/\/www.studiobrancaleone.it\/news\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\/","title":{"rendered":"RAEE, chiarimenti Cdc su nuovi raggruppamenti"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Il <strong>Centro di coordinamento Raee<\/strong> ha pubblicato l\u2019interpretazione applicativa del <a href=\"https:\/\/www.studiobrancaleone.it\/news\/raee-ridefiniti-i-raggruppamenti\/\">Decreto 40\/2023<\/a>, che ridefinisce i <strong>raggruppamenti di rifiuti elettrici ed elettronici (Raee)<\/strong> effettuati dai centri di raccolta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019interpretazione applicativa del decreto, rivolta a tutti i soggetti interessati alla gestione di AEE e RAEE, <strong>tiene conto dell\u2019elenco aggiornato di AEE<\/strong> di cui alla delibera del Comitato di Vigilanza e Controllo sulla gestione dei RAEE e delle pile, degli accumulatori e dei relativi rifiuti del 19 luglio 2018.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il documento, quindi, riporta i <strong>raggruppamenti di RAEE che devono essere effettuati<\/strong>, tenendo conto anche della correzione pubblicata il 21 aprile 2023 dal Mase nella nota che si riporta:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si segnala un refuso nell\u2019Allegato 1 al citato decreto: il &#8220;Raggruppamento 2&#8243; include erroneamente il paragrafo \u201c4.5 apparecchiature di grandi dimensioni diverse da quelle elencate nel paragrafo 4 dell&#8217;allegato IV del decreto legislativo 14 marzo 2014, n. 49.&#8221;. Si tratta di un refuso, in quanto il medesimo paragrafo \u00e8 riportato correttamente anche nel \u201cRaggruppamento 4\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il Cdc comunica anche il rinnovo delle condizioni di servizio per il ritiro dei RAEE presso i Grandi Utilizzatori. In particolare, il documento che regola il rapporto tra il CdC RAEE, i Sistemi Collettivi dei Produttori di AEE e i Grandi Utilizzatori in materia di gestione dei RAEE \u00e8 stato rinnovato all\u2019insegna dell\u2019<strong>ampliamento delle categorie di rifiuti elettronici <\/strong>coinvolti <strong>e del numero e tipologia di soggetti<\/strong> che possono aderirvi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per approfondimenti, si rimanda alla <a href=\"https:\/\/www.cdcraee.it\/news\/rinnovate-le-condizioni-di-servizio-per-il-ritiro-dei-raee-presso-i-grandi-utilizzatori\/\" target=\"_blank\" rel=\"noreferrer noopener\">pagina del Cdc<\/a>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-ast-global-color-0-color has-alpha-channel-opacity has-ast-global-color-0-background-color has-background is-style-wide\"\/>\n\n\n\n<h4 class=\"wp-block-heading\"><a href=\"https:\/\/h5u9y7p2.stackpathcdn.com\/wp-content\/uploads\/2023\/05\/Prot-11.2023-Comunicazione-CdC-RAEE-per-Decreto-40-2023-raggruppamenti.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Centro di coordinamento Raee &#8211; Prot. 11\/2023<\/a><\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Oggetto: Decreto 20 febbraio 2023 n. 40 Regolamento recante l\u2019aggiornamento dei raggruppamenti di rifiuti da apparecchiature elettriche ed elettroniche indicati nell\u2019Allegato 1 del decreto 25 settembre 2007, n. 185.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Centro di coordinamento Raee ha pubblicato l\u2019interpretazione applicativa del Decreto 40\/2023, che ridefinisce i raggruppamenti di rifiuti elettrici ed elettronici (Raee) effettuati dai centri di raccolta. L\u2019interpretazione applicativa del decreto, rivolta a tutti i soggetti interessati alla gestione di AEE e RAEE, tiene conto dell\u2019elenco aggiornato di AEE di cui alla delibera del Comitato [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":null,"ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[4],"tags":[163],"class_list":["post-9323","post","type-post","status-publish","format-standard","hentry","category-nazionali-ue","tag-raee"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>RAEE, chiarimenti Cdc su nuovi raggruppamenti &#060; Studio Brancaleone<\/title>\r\n<meta name=\"description\" content=\"Il Cdc Raee ha pubblicato l\u2019interpretazione sul Dm 40\/2023, che ridefinisce i raggruppamenti di rifiuti elettrici ed elettronici effettuati dai centri di raccolta.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.studiobrancaleone.it\/news\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"RAEE, chiarimenti Cdc su nuovi raggruppamenti &#060; Studio Brancaleone\" \/>\r\n<meta property=\"og:description\" content=\"Il Cdc Raee ha pubblicato l\u2019interpretazione sul Dm 40\/2023, che ridefinisce i raggruppamenti di rifiuti elettrici ed elettronici effettuati dai centri di raccolta.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.studiobrancaleone.it\/news\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Studio Brancaleone\" \/>\r\n<meta property=\"article:published_time\" content=\"2023-05-15T07:00:45+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-01-26T18:01:54+00:00\" \/>\r\n<meta name=\"author\" content=\"Giorgio Ferrari\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Giorgio Ferrari\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\\\/\"},\"author\":{\"name\":\"Giorgio Ferrari\",\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/#\\\/schema\\\/person\\\/da5920864810e22fb65389a0a5cff7e3\"},\"headline\":\"RAEE, chiarimenti Cdc su nuovi raggruppamenti\",\"datePublished\":\"2023-05-15T07:00:45+00:00\",\"dateModified\":\"2025-01-26T18:01:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\\\/\"},\"wordCount\":265,\"publisher\":{\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/#organization\"},\"keywords\":[\"Rifiuti &gt; Raee\"],\"articleSection\":[\"Nazionali\\\/Ue\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\\\/\",\"url\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\\\/\",\"name\":\"RAEE, chiarimenti Cdc su nuovi raggruppamenti &#060; Studio Brancaleone\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/#website\"},\"datePublished\":\"2023-05-15T07:00:45+00:00\",\"dateModified\":\"2025-01-26T18:01:54+00:00\",\"description\":\"Il Cdc Raee ha pubblicato l\u2019interpretazione sul Dm 40\\\/2023, che ridefinisce i raggruppamenti di rifiuti elettrici ed elettronici effettuati dai centri di raccolta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RAEE, chiarimenti Cdc su nuovi raggruppamenti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/#website\",\"url\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/\",\"name\":\"Studio Brancaleone\",\"description\":\"Notizie giuridiche aggiornate regolarmente\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/#organization\",\"name\":\"Studio Brancaleone\",\"url\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Testata-sito-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/Testata-sito-scaled.webp\",\"width\":2560,\"height\":481,\"caption\":\"Studio Brancaleone\"},\"image\":{\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/#\\\/schema\\\/person\\\/da5920864810e22fb65389a0a5cff7e3\",\"name\":\"Giorgio Ferrari\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5a8c666e3c03788ccd80843664b7c6eb2fb548eb37bb5cd6598134bf5d56ae1?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5a8c666e3c03788ccd80843664b7c6eb2fb548eb37bb5cd6598134bf5d56ae1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e5a8c666e3c03788ccd80843664b7c6eb2fb548eb37bb5cd6598134bf5d56ae1?s=96&d=mm&r=g\",\"caption\":\"Giorgio Ferrari\"},\"sameAs\":[\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\"],\"url\":\"https:\\\/\\\/www.studiobrancaleone.it\\\/news\\\/author\\\/giorfer\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RAEE, chiarimenti Cdc su nuovi raggruppamenti &#060; Studio Brancaleone","description":"Il Cdc Raee ha pubblicato l\u2019interpretazione sul Dm 40\/2023, che ridefinisce i raggruppamenti di rifiuti elettrici ed elettronici effettuati dai centri di raccolta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.studiobrancaleone.it\/news\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\/","og_locale":"it_IT","og_type":"article","og_title":"RAEE, chiarimenti Cdc su nuovi raggruppamenti &#060; Studio Brancaleone","og_description":"Il Cdc Raee ha pubblicato l\u2019interpretazione sul Dm 40\/2023, che ridefinisce i raggruppamenti di rifiuti elettrici ed elettronici effettuati dai centri di raccolta.","og_url":"https:\/\/www.studiobrancaleone.it\/news\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\/","og_site_name":"Studio Brancaleone","article_published_time":"2023-05-15T07:00:45+00:00","article_modified_time":"2025-01-26T18:01:54+00:00","author":"Giorgio Ferrari","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Giorgio Ferrari","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.studiobrancaleone.it\/news\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\/#article","isPartOf":{"@id":"https:\/\/www.studiobrancaleone.it\/news\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\/"},"author":{"name":"Giorgio Ferrari","@id":"https:\/\/www.studiobrancaleone.it\/news\/#\/schema\/person\/da5920864810e22fb65389a0a5cff7e3"},"headline":"RAEE, chiarimenti Cdc su nuovi raggruppamenti","datePublished":"2023-05-15T07:00:45+00:00","dateModified":"2025-01-26T18:01:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.studiobrancaleone.it\/news\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\/"},"wordCount":265,"publisher":{"@id":"https:\/\/www.studiobrancaleone.it\/news\/#organization"},"keywords":["Rifiuti &gt; Raee"],"articleSection":["Nazionali\/Ue"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.studiobrancaleone.it\/news\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\/","url":"https:\/\/www.studiobrancaleone.it\/news\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\/","name":"RAEE, chiarimenti Cdc su nuovi raggruppamenti &#060; Studio Brancaleone","isPartOf":{"@id":"https:\/\/www.studiobrancaleone.it\/news\/#website"},"datePublished":"2023-05-15T07:00:45+00:00","dateModified":"2025-01-26T18:01:54+00:00","description":"Il Cdc Raee ha pubblicato l\u2019interpretazione sul Dm 40\/2023, che ridefinisce i raggruppamenti di rifiuti elettrici ed elettronici effettuati dai centri di raccolta.","breadcrumb":{"@id":"https:\/\/www.studiobrancaleone.it\/news\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.studiobrancaleone.it\/news\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.studiobrancaleone.it\/news\/raee-chiarimenti-cdc-su-nuovi-raggruppamenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.studiobrancaleone.it\/news\/"},{"@type":"ListItem","position":2,"name":"RAEE, chiarimenti Cdc su nuovi raggruppamenti"}]},{"@type":"WebSite","@id":"https:\/\/www.studiobrancaleone.it\/news\/#website","url":"https:\/\/www.studiobrancaleone.it\/news\/","name":"Studio Brancaleone","description":"Notizie giuridiche aggiornate regolarmente","publisher":{"@id":"https:\/\/www.studiobrancaleone.it\/news\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.studiobrancaleone.it\/news\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.studiobrancaleone.it\/news\/#organization","name":"Studio Brancaleone","url":"https:\/\/www.studiobrancaleone.it\/news\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.studiobrancaleone.it\/news\/#\/schema\/logo\/image\/","url":"https:\/\/www.studiobrancaleone.it\/news\/wp-content\/uploads\/2025\/02\/Testata-sito-scaled.webp","contentUrl":"https:\/\/www.studiobrancaleone.it\/news\/wp-content\/uploads\/2025\/02\/Testata-sito-scaled.webp","width":2560,"height":481,"caption":"Studio Brancaleone"},"image":{"@id":"https:\/\/www.studiobrancaleone.it\/news\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.studiobrancaleone.it\/news\/#\/schema\/person\/da5920864810e22fb65389a0a5cff7e3","name":"Giorgio Ferrari","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e5a8c666e3c03788ccd80843664b7c6eb2fb548eb37bb5cd6598134bf5d56ae1?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e5a8c666e3c03788ccd80843664b7c6eb2fb548eb37bb5cd6598134bf5d56ae1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5a8c666e3c03788ccd80843664b7c6eb2fb548eb37bb5cd6598134bf5d56ae1?s=96&d=mm&r=g","caption":"Giorgio Ferrari"},"sameAs":["https:\/\/www.studiobrancaleone.it\/news"],"url":"https:\/\/www.studiobrancaleone.it\/news\/author\/giorfer\/"}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Giorgio Ferrari","author_link":"https:\/\/www.studiobrancaleone.it\/news\/author\/giorfer\/"},"uagb_comment_info":0,"uagb_excerpt":"Il Centro di coordinamento Raee ha pubblicato l\u2019interpretazione applicativa del Decreto 40\/2023, che ridefinisce i raggruppamenti di rifiuti elettrici ed elettronici (Raee) effettuati dai centri di raccolta. L\u2019interpretazione applicativa del decreto, rivolta a tutti i soggetti interessati alla gestione di AEE e RAEE, tiene conto dell\u2019elenco aggiornato di AEE di cui alla delibera del Comitato&hellip;","_links":{"self":[{"href":"https:\/\/www.studiobrancaleone.it\/news\/wp-json\/wp\/v2\/posts\/9323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.studiobrancaleone.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.studiobrancaleone.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.studiobrancaleone.it\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.studiobrancaleone.it\/news\/wp-json\/wp\/v2\/comments?post=9323"}],"version-history":[{"count":0,"href":"https:\/\/www.studiobrancaleone.it\/news\/wp-json\/wp\/v2\/posts\/9323\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.studiobrancaleone.it\/news\/wp-json\/wp\/v2\/media?parent=9323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.studiobrancaleone.it\/news\/wp-json\/wp\/v2\/categories?post=9323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.studiobrancaleone.it\/news\/wp-json\/wp\/v2\/tags?post=9323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}